{"id":2674,"count":12,"description":"Tonstudio Dienstleistungen von Studio Longboard. Musikaufnahmen, Sprachaufnahmen, Band-Aufnahmen, Mixing, Mastering, Live-Recording, Vermietung, Proberaumnutzung ob stundenweise oder mehrere Tage am St\u00fcck. \r\nIhr sucht ein professionelles Tonstudio oder Proberaum mitten in Hamburg mit gro\u00dfz\u00fcgigen R\u00e4umlichkeiten, erfahrenem und freundlichem Personal und qualitativ- hochwertigem Aufnahme- und Musikequipment? Studio Longboard - wir helfen euch euer Projekt ins Rollen zu bringen.","link":"https:\/\/www.studiolongboard.com\/en\/produkt-kategorie\/tonstudio-dienstleistungen\/","name":"Recording studio offers","slug":"recording-studio-services","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":215,"_links":{"self":[{"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/product_cat\/2674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/product?product_cat=2674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}