{"id":9900,"date":"2020-04-14T18:26:20","date_gmt":"2020-04-14T16:26:20","guid":{"rendered":"https:\/\/www.studiolongboard.com\/?p=9900"},"modified":"2020-07-29T20:06:18","modified_gmt":"2020-07-29T18:06:18","slug":"die-audio-trickkiste-teil-4-der-lautsprecher","status":"publish","type":"post","link":"https:\/\/www.studiolongboard.com\/en\/die-audio-trickkiste-teil-4-der-lautsprecher\/","title":{"rendered":"Die Audio Trickkiste &#8211; Teil 4 &#8222;Der Lautsprecher&#8220;"},"content":{"rendered":"<p style=\"text-align: center;\">Der unkonventionelle Einsatz von Audioger\u00e4ten &#8211; von Florian Rosnau<\/p>\n<p>Lautsprecher und Mikrofone dienen zur Wandlung von Schall zu elektromagnetischen Schwingungen, jeweils in unterschiedliche Richtungen. Da sie vom Prinzip her den gleichen Aufbau haben, kann man sie auch umgekehrt nutzen: das Mikrofon wird zum Lautsprecher und der Lautsprecher zum Mikrofon.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Das l\u00e4sst sich prima beim Recording verwenden: ein Lautsprecher als \u00dcber-Gro\u00dfmembran-Mikrofon, der besonders gut tiefe Frequenzen aufnimmt.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Stellt man ihn vor die Bassdrum, bekommt man ein sehr wuchtiges Signal, das an eine Bassdrum aus einem Drumcomputer erinnert. Dieses \u201eMikrofon\u201c zu den anderen Bassdrum-Mikrofonen zugemischt ergibt eine Menge Low-End. Darum wird ein solches Lautsprecher-Mikrofon oft als Subkick-Mikrofon bezeichnet. Auch vor der Box des Bassverst\u00e4rkers kann ein Lautsprecher-Mikrofon einen satten Bassklang erzielen.<\/p>\n<p>Dabei sollte man vor der Aufnahme mit dem Abstand zur Bassdrum experimentieren, bis man eine Stelle gefunden hat, an<span class=\"Apple-converted-space\">\u00a0<\/span>der viel Tiefbass-Anteil gewonnen wird. Der Selbstbau ist einfach zu bew\u00e4ltigen und erfordert neben wenig Material nur einfache L\u00f6tkenntnisse. Erst w\u00e4hlt man einen herk\u00f6mmlichen Tauchspulen-Lautsprecher. Die Gr\u00f6\u00dfe der Membran ist frei w\u00e4hlbar und l\u00e4dt zum Experimentieren ein. An die elektrischen Anschl\u00fcsse l\u00f6tet man ein einfaches Mikrofonkabel. F\u00fcr einen XLR-Anschluss wird der positive Anschluss auf Pin 2 und der negative auf Pin 1 gelegt, die Kabelabschirmung kann man mit Pin 3 verbinden.\u00a0Sehr elegant ist der Einbau in einen alten Tom-Kessel (siehe Abb.). Dort lassen sich ohne Schwierigkeiten Halterungen f\u00fcr den Lautsprecher und eine XLR-Buchse einbauen und zudem ist eine Halterung f\u00fcr einen kleinen St\u00e4nder vorhanden, wie man ihn f\u00fcr die Snare benutzt.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Die Signale aus dem Lautsprecher k\u00f6nnen sehr stark sein, weswegen im Signalweg eine M\u00f6glichkeit zur Abd\u00e4mpfung vorhanden sein sollte, beispielsweise im Mikrofon-Preamp. Eine andere M\u00f6glichkeit w\u00e4re den Lautsprecher \u00fcber Klinkensteckverbindung in eine DI-Box zu schicken, bevor das Signal in den Vorverst\u00e4rker gelangt.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p style=\"text-align: left;\">Viel Spa\u00df beim Ausprobieren!<\/p>\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.studiolongboard.com\/wp-content\/uploads\/2020\/06\/SL-Recording_web-P1070245.jpg\" alt=\"\" class=\"wp-image-10924\" srcset=\"https:\/\/www.studiolongboard.com\/wp-content\/uploads\/2020\/06\/SL-Recording_web-P1070245.jpg 600w, https:\/\/www.studiolongboard.com\/wp-content\/uploads\/2020\/06\/SL-Recording_web-P1070245-100x100.jpg 100w, https:\/\/www.studiolongboard.com\/wp-content\/uploads\/2020\/06\/SL-Recording_web-P1070245-510x510.jpg 510w, https:\/\/www.studiolongboard.com\/wp-content\/uploads\/2020\/06\/SL-Recording_web-P1070245-150x150.jpg 150w, https:\/\/www.studiolongboard.com\/wp-content\/uploads\/2020\/06\/SL-Recording_web-P1070245-300x300.jpg 300w, https:\/\/www.studiolongboard.com\/wp-content\/uploads\/2020\/06\/SL-Recording_web-P1070245-145x145.jpg 145w, https:\/\/www.studiolongboard.com\/wp-content\/uploads\/2020\/06\/SL-Recording_web-P1070245-236x236.jpg 236w, https:\/\/www.studiolongboard.com\/wp-content\/uploads\/2020\/06\/SL-Recording_web-P1070245-435x435.jpg 435w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption>Drums recording at Studio Longboard<\/figcaption><\/figure><\/div>\n\n\n\n<p><a href=\"https:\/\/www.studiolongboard.com\/die-audio-trickkiste-teil-3-autopan-mal-anders\/\">Die Audio Trickkiste &#8211; Teil 3<\/a><\/p>\n\n\n<div data-block-name=\"woocommerce\/handpicked-products\" data-content-visibility=\"{&quot;title&quot;:true,&quot;price&quot;:true,&quot;rating&quot;:true,&quot;button&quot;:false}\" data-edit-mode=\"false\" data-products=\"[6728,6464,6622]\" class=\"wc-block-grid wp-block-handpicked-products wp-block-woocommerce-handpicked-products wc-block-handpicked-products has-3-columns has-multiple-rows alignwide\"><ul class=\"wc-block-grid__products\"><li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.studiolongboard.com\/en\/shop\/tonstudio-dienstleistungen\/aufnahmeraum-mieten\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"296\" src=\"https:\/\/www.studiolongboard.com\/wp-content\/uploads\/2014\/12\/Proberaum-StudioLongboard_2000p-e1548178006506-247x296.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Aufnahmeraum\/Proberaum tageweise buchen\"><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Aufnahmeraum\/Proberaum tageweise buchen<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\">From: <span class=\"woocommerce-Price-amount amount\">149,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div><p class=\"wc-gzd-additional-info wc-gzd-additional-info-loop tax-info\">incl. VAT<\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/li>\n<li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.studiolongboard.com\/en\/shop\/tonstudio-dienstleistungen\/regieraum-mieten\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"296\" src=\"https:\/\/www.studiolongboard.com\/wp-content\/uploads\/2019\/02\/Studiolongboard-_8-Regieraum-247x296.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Regieraum mieten\"><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Regieraum mieten<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\">From: <span class=\"woocommerce-Price-amount amount\">209,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div><p class=\"wc-gzd-additional-info wc-gzd-additional-info-loop tax-info\">incl. VAT<\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/li>\n<li class=\"wc-block-grid__product\">\n\t\t\t\t<a href=\"https:\/\/www.studiolongboard.com\/en\/shop\/tonstudio-dienstleistungen\/professionelle-bandaufnahme-im-tonstudio\/\" class=\"wc-block-grid__product-link\">\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"wc-block-grid__product-image\"><img loading=\"lazy\" decoding=\"async\" width=\"247\" height=\"296\" src=\"https:\/\/www.studiolongboard.com\/wp-content\/uploads\/2019\/01\/Studiolongboard-_9-e1637840181406-247x296.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Professionelle Band-Aufnahme im Tonstudio\"><\/div>\n\t\t\t\t\t<div class=\"wc-block-grid__product-title\">Professionelle Band-Aufnahme im Tonstudio<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"wc-block-grid__product-price price\">From: <span class=\"woocommerce-Price-amount amount\">489,90&nbsp;<span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span><\/span><\/div><p class=\"wc-gzd-additional-info wc-gzd-additional-info-loop tax-info\">incl. VAT<\/p>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/li>\n<\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Der unkonventionelle Einsatz von Audioger\u00e4ten &#8211; von Florian Rosnau Lautsprecher und Mikrofone dienen zur Wandlung von Schall zu elektromagnetischen Schwingungen, jeweils in unterschiedliche Richtungen. Da sie vom Prinzip her den gleichen Aufbau haben, kann man sie auch umgekehrt nutzen: das Mikrofon wird zum Lautsprecher und der Lautsprecher zum Mikrofon.\u00a0 Das l\u00e4sst sich prima beim Recording [&#8230;]\n","protected":false},"author":2,"featured_media":10922,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"Die Audio Trickkiste - Teil 4 \"Der Lautsprecher\"\nDer unkonventionelle Einsatz von Audioger\u00e4ten - von Florian Rosnau","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[199,1,114,82],"tags":[4923,6571,6572,5583],"class_list":["post-9900","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aufnahmen-aufnahmen","category-studio-longboard-blog","category-tonstudio-blog","category-workshop","tag-audio-trickkiste","tag-lautsprecher","tag-mikrofon","tag-sub-kick"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.studiolongboard.com\/wp-content\/uploads\/2020\/04\/Die-Audio-Trickkiste-Sub-Kick-1.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9sVj6-2zG","_links":{"self":[{"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/posts\/9900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/comments?post=9900"}],"version-history":[{"count":0,"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/posts\/9900\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/media\/10922"}],"wp:attachment":[{"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/media?parent=9900"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/categories?post=9900"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiolongboard.com\/en\/wp-json\/wp\/v2\/tags?post=9900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}